{"id":57755,"date":"2026-07-15T05:26:32","date_gmt":"2026-07-15T13:26:32","guid":{"rendered":"https:\/\/namiradalei.com.br\/barradobugres\/?p=57755"},"modified":"2026-07-15T05:26:32","modified_gmt":"2026-07-15T13:26:32","slug":"desenvolvimento-tambem-nasce-do-que-a-sociedade-descarta","status":"publish","type":"post","link":"https:\/\/namiradalei.com.br\/barradobugres\/desenvolvimento-tambem-nasce-do-que-a-sociedade-descarta\/","title":{"rendered":"Desenvolvimento tamb\u00e9m nasce do que a sociedade descarta"},"content":{"rendered":"<p><strong><em><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-57756 size-full\" src=\"https:\/\/namiradalei.com.br\/barradobugres\/wp-content\/uploads\/2026\/07\/IMG-20260702-WA0132-e1784121941759.jpg\" alt=\"\" width=\"1000\" height=\"934\" \/>Por Iraj\u00e1 Lacerda<\/em><\/strong><\/p>\n<p>H\u00e1 um dado que merece nossa profunda reflex\u00e3o: o Brasil recicla apenas 2,2% dos res\u00edduos s\u00f3lidos urbanos que produz. Menos de 3% de tudo o que consumimos e descartamos retorna \u00e0 cadeia produtiva. O n\u00famero impressiona e revela quanto o pa\u00eds ainda desperdi\u00e7a uma oportunidade de gerar emprego, renda, reduzir gastos p\u00fablicos e preservar o meio ambiente.<\/p>\n<p>A reciclagem precisa entrar definitivamente na agenda das pol\u00edticas p\u00fablicas. Ela n\u00e3o pode depender apenas da boa vontade de quem separa o lixo em casa nem do esfor\u00e7o di\u00e1rio e, muitas vezes, solit\u00e1rio dos catadores. Prefeitos, vereadores, deputados e gestores precisam incentivar a coleta seletiva, fortalecer associa\u00e7\u00f5es e cooperativas, ampliar a educa\u00e7\u00e3o ambiental nas escolas e buscar recursos para desenvolver toda a cadeia.<\/p>\n<p>O Plano Nacional de Res\u00edduos S\u00f3lidos estabelece a meta ambiciosa de recuperar cerca de metade dos res\u00edduos urbanos at\u00e9 2040. Isso demonstra que transformar lixo em riqueza virou uma necessidade. \u00c9 aqui que entra a economia circular: um modelo que substitui o h\u00e1bito de &#8220;extrair, produzir e descartar&#8221; por um ciclo inteligente, onde o res\u00edduo de hoje se transforma na mat\u00e9ria-prima de amanh\u00e3.<\/p>\n<p>Em Mato Grosso, esse potencial \u00e9 imenso. Pesquisa do Sebrae MT em 2025 aponta que as cooperativas locais reciclam, juntas, cerca de 620 toneladas de materiais por m\u00eas. O levantamento, contudo, revela um gargalo: apenas 21% delas possuem contratos formais com prefeituras ou empresas, evidenciando a urg\u00eancia de estruturar o setor.<\/p>\n<p>C\u00e1ceres nos d\u00e1 um bom exemplo de que \u00e9 poss\u00edvel mudar essa realidade. A Associa\u00e7\u00e3o de Catadores de Materiais Recicl\u00e1veis de C\u00e1ceres (Ascarc), que tamb\u00e9m atende Campos de J\u00falio e Conquista d&#8217;Oeste, recolhe, em C\u00e1ceres, uma m\u00e9dia de 160 toneladas de materiais recicl\u00e1veis por m\u00eas. Reunindo cerca de 100 associados e mais de 50 catadores aut\u00f4nomos, o trabalho da Ascarc &#8211; reconhecido como de utilidade p\u00fablica municipal e estadual &#8211; demonstra que investir na reciclagem \u00e9 gerar inclus\u00e3o social e dignidade \u00e0s comunidades envolvidas.<\/p>\n<p>Para que esses exemplos se multipliquem, o ciclo 2026 da Lei de Incentivo \u00e0 Reciclagem, aberto pelo Governo Federal, surge como oportunidade concreta. O mecanismo permite que munic\u00edpios e cooperativas apresentem projetos para modernizar estruturas, adquirir equipamentos e ampliar a coleta.<\/p>\n<p>Afinal, por tr\u00e1s de qualquer recurso, est\u00e3o as pessoas que fazem a engrenagem girar. Os catadores prestam um servi\u00e7o essencial \u00e0 sa\u00fade p\u00fablica, mas ainda recebem pouco reconhecimento. Valoriz\u00e1-los significa oferecer condi\u00e7\u00f5es dignas de trabalho, seguran\u00e7a e remunera\u00e7\u00e3o justa, al\u00e9m de incentivar uma cultura em que separar corretamente os res\u00edduos seja um h\u00e1bito que protege o meio ambiente e o futuro das pr\u00f3ximas gera\u00e7\u00f5es.<\/p>\n<p>Desenvolvimento sustent\u00e1vel n\u00e3o \u00e9 apenas produzir mais. \u00c9 produzir melhor, desperdi\u00e7ar menos e criar oportunidades para quem transforma o descarte em sustento. Mato Grosso j\u00e1 consolidou sua lideran\u00e7a hist\u00f3rica na produ\u00e7\u00e3o agropecu\u00e1ria. Agora, tem a oportunidade de se tornar tamb\u00e9m uma refer\u00eancia nacional em economia circular.&#8221;<\/p>\n<p><strong><em>Iraj\u00e1 Lacerda \u00e9 ex-secret\u00e1rio executivo do Minist\u00e9rio da Agricultura e Pecu\u00e1ria e ex-presidente da Comiss\u00e3o de Direito Agr\u00e1rio da OAB-MT<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Iraj\u00e1 Lacerda H\u00e1 um dado que merece nossa profunda reflex\u00e3o: o Brasil recicla apenas 2,2% dos res\u00edduos s\u00f3lidos urbanos<\/p>\n","protected":false},"author":1,"featured_media":57756,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[8,6],"tags":[],"class_list":["post-57755","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques","category-opiniao"],"_links":{"self":[{"href":"https:\/\/namiradalei.com.br\/barradobugres\/wp-json\/wp\/v2\/posts\/57755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/namiradalei.com.br\/barradobugres\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/namiradalei.com.br\/barradobugres\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/namiradalei.com.br\/barradobugres\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/namiradalei.com.br\/barradobugres\/wp-json\/wp\/v2\/comments?post=57755"}],"version-history":[{"count":1,"href":"https:\/\/namiradalei.com.br\/barradobugres\/wp-json\/wp\/v2\/posts\/57755\/revisions"}],"predecessor-version":[{"id":57757,"href":"https:\/\/namiradalei.com.br\/barradobugres\/wp-json\/wp\/v2\/posts\/57755\/revisions\/57757"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/namiradalei.com.br\/barradobugres\/wp-json\/wp\/v2\/media\/57756"}],"wp:attachment":[{"href":"https:\/\/namiradalei.com.br\/barradobugres\/wp-json\/wp\/v2\/media?parent=57755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/namiradalei.com.br\/barradobugres\/wp-json\/wp\/v2\/categories?post=57755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/namiradalei.com.br\/barradobugres\/wp-json\/wp\/v2\/tags?post=57755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}